{"id":33266,"date":"2026-01-10T07:00:04","date_gmt":"2026-01-10T06:00:04","guid":{"rendered":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/assistant-agence-h-f-noyon-h-f"},"modified":"2026-01-10T07:00:04","modified_gmt":"2026-01-10T06:00:04","slug":"assistant-agence-h-f-noyon-h-f","status":"publish","type":"job_listing","link":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/assistant-agence-h-f-noyon-h-f","title":{"rendered":"Assistant Agence H\/F &#8211; Noyon H\/F"},"content":{"rendered":"<h2>L&rsquo;entreprise:<\/h2>\n<p>Action Logement Groupe d\u00e9termine les orientations strat\u00e9giques du groupe Action Logement, les conditions d&#8217;emploi des ressources financi\u00e8res, et veille \u00e0 ce que les aides et les services soient distribu\u00e9s avec \u00e9quit\u00e9 entre les personnes \u00e9ligibles, dans tous les territoires.<\/p>\n<h2>Description:<\/h2>\n<\/p>\n<p>Support essentiel de l\u2019\u00e9quipe terrain, vous coordonnez les activit\u00e9s administrative et technique, facilitez le suivi des dossiers des locataires et leur assurez un accueil de qualit\u00e9.<\/p>\n<p>Plus pr\u00e9cis\u00e9ment, vos missions principales sont les suivantes :<\/p>\n<p>\u2022 Assurer l&rsquo;accueil t\u00e9l\u00e9phonique et physique des fournisseurs et locataires<\/p>\n<p>\u2022 G\u00e9rer les stocks de fournitures en lien avec les services g\u00e9n\u00e9raux<\/p>\n<p>\u2022 Accompagner les demandeurs dans la constitution de leur dossier de demande de logement<\/p>\n<p>\u2022 R\u00e9diger les comptes-rendus de r\u00e9union<\/p>\n<p>\u2022 Intervenir en appui des charg\u00e9s de client\u00e8le et gestionnaires de proximit\u00e9 sur le traitement desappels CRC et autres r\u00e9clamations<\/p>\n<p>\u2022 Assurer la gestion du courrier et des mails destin\u00e9s \u00e0 l&rsquo;agence<\/p>\n<p>\u2022 R\u00e9aliser des enqu\u00eates de satisfaction post interventions<\/p>\n<p>\u2022 R\u00e9aliser la signature de baux<\/p>\n<p>\u2022 R\u00e9aliser les actes administratifs post attributions<\/p>\n<p>\u2022 Assurer la gestion des Ordres de Service<\/p>\n<p>\u2022 Organiser le planning des \u00e9quipes de l&rsquo;agence<\/p>\n<p>\u2022 Planifier et assurer l&rsquo;organisation logistique des rendez-vous avec les prestataires<\/p>\n<p>\u2022 Assurer la gestion administrative des bons de commandes en lien avec le service comptabilit\u00e9.<\/p>\n<p>Le poste est bas\u00e9 au sein de l\u2019antenne de Noyon (60), rattach\u00e9e \u00e0 l\u2019agence de Compi\u00e8gne (60)<\/p>\n<h2>Profil:<\/h2>\n<\/p>\n<p>Vous justifiez d\u2019un BAC+2 en Assistanat ou \u00e9quivalent, compl\u00e9t\u00e9 par une exp\u00e9rience significative sur une fonction similaire acquise en agence immobili\u00e8re ou chez un bailleur social. Vous ma\u00eetrisez les outils informatiques (PackOffice) et disposez d\u2019aptitudes relationnelles et r\u00e9dactionnelles av\u00e9r\u00e9es. Votre sens de l&rsquo;organisation et votre r\u00e9activit\u00e9, associ\u00e9s \u00e0 votre rigueur et \u00e0 votre autonomie, seront des atouts ind\u00e9niables pour r\u00e9ussir sur ce poste<\/p>\n<h3>Niveau de dipl\u00f4me:<\/h3>\n<p> BAC + 2 (BTS, DUT, DEUG, etc)<\/p>\n<h3>Sp\u00e9cialisations:<\/h3>\n<p>Secr\u00e9tariat\/Gestion administrative<\/p>\n","protected":false},"author":0,"featured_media":3646,"template":"","meta":{"_promoted":"","_job_location":"France, Hauts-de-France, 60 - Oise Noyon","_application":"https:\/\/actionlogement-recrute.talent-soft.com\/offre-de-emploi\/emploi-assistant-agence-h-f-noyon-h-f_16756.aspx?utm_source=monbailleur.fr","_company_name":"Action Logement","_company_website":"https:\/\/actionlogement-recrute.talent-soft.com\/","_company_tagline":"","_company_twitter":"","_company_video":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job-categories":[78],"job-types":[63],"class_list":{"0":"post-33266","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"has-post-thumbnail","5":"hentry","6":"job_listing_category-autres","7":"job_listing_type-cdi","9":"job-type-cdi"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.4 (Yoast SEO v25.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Assistant Agence H\/F - Noyon H\/F - Monbailleur.fr - Emploi<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assistant Agence H\/F - Noyon H\/F\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;entreprise: Action Logement Groupe d\u00e9termine les orientations strat\u00e9giques du groupe Action Logement, les conditions d&#8217;emploi des ressources financi\u00e8res, et veille \u00e0 ce que les aides et les services soient distribu\u00e9s avec \u00e9quit\u00e9 entre les personnes \u00e9ligibles, dans tous les territoires. Description: Support essentiel de l\u2019\u00e9quipe terrain, vous coordonnez les activit\u00e9s administrative et technique, facilitez le\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/assistant-agence-h-f-noyon-h-f\" \/>\n<meta property=\"og:site_name\" content=\"Monbailleur.fr - Emploi\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/action-logement.png\" \/>\n\t<meta property=\"og:image:width\" content=\"175\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/assistant-agence-h-f-noyon-h-f\",\"url\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/assistant-agence-h-f-noyon-h-f\",\"name\":\"Assistant Agence H\/F - Noyon H\/F - Monbailleur.fr - Emploi\",\"isPartOf\":{\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/assistant-agence-h-f-noyon-h-f#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/assistant-agence-h-f-noyon-h-f#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/action-logement.png\",\"datePublished\":\"2026-01-10T06:00:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/assistant-agence-h-f-noyon-h-f#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/assistant-agence-h-f-noyon-h-f\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/assistant-agence-h-f-noyon-h-f#primaryimage\",\"url\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/action-logement.png\",\"contentUrl\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/action-logement.png\",\"width\":175,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/assistant-agence-h-f-noyon-h-f#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"offres d\u2019emploi\",\"item\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/job-listings\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Assistant Agence H\/F &#8211; Noyon H\/F\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/#website\",\"url\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/\",\"name\":\"Monbailleur.fr - Emploi\",\"description\":\"Les offres d&#039;emploi du logement social\",\"publisher\":{\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/#organization\",\"name\":\"Monbailleur.fr - Emploi\",\"url\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/MonBailleur-1200x675-1.png\",\"contentUrl\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/MonBailleur-1200x675-1.png\",\"width\":1200,\"height\":675,\"caption\":\"Monbailleur.fr - Emploi\"},\"image\":{\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Assistant Agence H\/F - Noyon H\/F - Monbailleur.fr - Emploi","robots":{"index":"noindex","follow":"follow"},"og_locale":"fr_FR","og_type":"article","og_title":"Assistant Agence H\/F - Noyon H\/F","og_description":"L&rsquo;entreprise: Action Logement Groupe d\u00e9termine les orientations strat\u00e9giques du groupe Action Logement, les conditions d&#8217;emploi des ressources financi\u00e8res, et veille \u00e0 ce que les aides et les services soient distribu\u00e9s avec \u00e9quit\u00e9 entre les personnes \u00e9ligibles, dans tous les territoires. Description: Support essentiel de l\u2019\u00e9quipe terrain, vous coordonnez les activit\u00e9s administrative et technique, facilitez le","og_url":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/assistant-agence-h-f-noyon-h-f","og_site_name":"Monbailleur.fr - Emploi","og_image":[{"width":175,"height":200,"url":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/action-logement.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/assistant-agence-h-f-noyon-h-f","url":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/assistant-agence-h-f-noyon-h-f","name":"Assistant Agence H\/F - Noyon H\/F - Monbailleur.fr - Emploi","isPartOf":{"@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/assistant-agence-h-f-noyon-h-f#primaryimage"},"image":{"@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/assistant-agence-h-f-noyon-h-f#primaryimage"},"thumbnailUrl":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/action-logement.png","datePublished":"2026-01-10T06:00:04+00:00","breadcrumb":{"@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/assistant-agence-h-f-noyon-h-f#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/assistant-agence-h-f-noyon-h-f"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/assistant-agence-h-f-noyon-h-f#primaryimage","url":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/action-logement.png","contentUrl":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/action-logement.png","width":175,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/assistant-agence-h-f-noyon-h-f#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.monbailleur.fr\/offres-emploi\/"},{"@type":"ListItem","position":2,"name":"offres d\u2019emploi","item":"https:\/\/www.monbailleur.fr\/offres-emploi\/job-listings"},{"@type":"ListItem","position":3,"name":"Assistant Agence H\/F &#8211; Noyon H\/F"}]},{"@type":"WebSite","@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/#website","url":"https:\/\/www.monbailleur.fr\/offres-emploi\/","name":"Monbailleur.fr - Emploi","description":"Les offres d&#039;emploi du logement social","publisher":{"@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.monbailleur.fr\/offres-emploi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/#organization","name":"Monbailleur.fr - Emploi","url":"https:\/\/www.monbailleur.fr\/offres-emploi\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/#\/schema\/logo\/image\/","url":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/MonBailleur-1200x675-1.png","contentUrl":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/MonBailleur-1200x675-1.png","width":1200,"height":675,"caption":"Monbailleur.fr - Emploi"},"image":{"@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/job-listings\/33266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/types\/job_listing"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/media\/3646"}],"wp:attachment":[{"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/media?parent=33266"}],"wp:term":[{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/job-categories?post=33266"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/job-types?post=33266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}