{"id":35116,"date":"2026-03-13T07:00:10","date_gmt":"2026-03-13T06:00:10","guid":{"rendered":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/conseiller-e-commercial-e-junior-alternance-strasbourg"},"modified":"2026-03-13T07:00:10","modified_gmt":"2026-03-13T06:00:10","slug":"conseiller-e-commercial-e-junior-alternance-strasbourg","status":"publish","type":"job_listing","link":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/conseiller-e-commercial-e-junior-alternance-strasbourg","title":{"rendered":"Conseiller.e commercial.e Junior (Alternance) &#8211; Strasbourg"},"content":{"rendered":"<h2>L&rsquo;entreprise:<\/h2>\n<p>Action Logement Groupe d\u00e9termine les orientations strat\u00e9giques du groupe Action Logement, les conditions d&#8217;emploi des ressources financi\u00e8res, et veille \u00e0 ce que les aides et les services soient distribu\u00e9s avec \u00e9quit\u00e9 entre les personnes \u00e9ligibles, dans tous les territoires.<\/p>\n<h2>Description:<\/h2>\n<\/p>\n<p><strong>A la rentr\u00e9e 2026, tu souhaites poursuivre ta formation en alternance dans une entreprise dynamique, o\u00f9 tu pourras apprendre, relever des d\u00e9fis et d\u00e9velopper tes comp\u00e9tences au sein d\u2019une \u00e9quipe engag\u00e9e ? <\/strong><\/p>\n<p><strong>Bonne nouvelle, tu es au bon endroit ! <\/strong><\/p>\n<p><strong>N\u00e9olia recherche pour son agence client\u00e8le de Strasbourg son futur : <\/strong><\/p>\n<\/p>\n<p style=\"text-align: center\"><span style=\"font-size: 12pt\"><strong>CONSEILLER.ERE COMMERCIAL.E JUNIOR (H\/F)<\/strong><\/span><\/p>\n<p>Nature du contrat : Contrat d\u2019apprentissage d&rsquo;1 \u00e0 2 ans selon le dipl\u00f4me pr\u00e9par\u00e9<\/p>\n<p>Date pr\u00e9visionnelle de prise de fonction : ao\u00fbt\/septembre 2026<\/p>\n<p>Salaire selon grilles d&rsquo;apprentissage <\/p>\n<\/p>\n<p><strong>Tes missions seront les suivantes : <\/strong><\/p>\n<p>En tant que profil \u00ab Junior \u00bb, sous la responsabilit\u00e9 du Responsable d\u2019Agence et sous le tutorat d\u2019une. Conseiller.e commercial.e, tu participes activement \u00e0 la vie commerciale de l\u2019agence :<\/p>\n<\/p>\n<p><strong>Commercialisation des logements et de leurs annexes :<\/strong><\/p>\n<p>&#8211; Prospecter, \u00e9tablir et entretenir des r\u00e9seaux de prospection (partenaires, collectivit\u00e9s, financeurs\u2026)<\/p>\n<p>&#8211; Mener les entretiens \u00ab d\u00e9couverte \u00bb des candidats \u00e0 la location <\/p>\n<p>&#8211; R\u00e9aliser la commercialisation des nouveaux programmes et des relocations<\/p>\n<p>&#8211; Traiter les r\u00e9clamations commerciales<\/p>\n<p>&#8211; Analyser les besoins exprim\u00e9s <\/p>\n<p>&#8211; Organiser et r\u00e9aliser les visites des logements <\/p>\n<p>&#8211; Pr\u00e9parer les Commissions d\u2019Attribution de Logements et Examen de l\u2019Occupation des Logements <\/p>\n<p>&#8211; Pr\u00e9parer les baux et annexes pour les rendez-vous de signature du bail<\/p>\n<p>&#8211; Organiser la planification des \u00e9tats des lieux entrants en lien avec le Manager de Proximit\u00e9 ou le gardien<\/p>\n<\/p>\n<p><strong>Gestion du client et traitement des r\u00e9clamations administratives :<\/strong><\/p>\n<p><strong>Gestion des entr\u00e9es et sorties des clients : <\/strong><\/p>\n<p>&#8211; G\u00e9rer les demandes de mutation de son secteur et la prise de rendez-vous pour l\u2019\u00e9tat des lieux d\u2019entr\u00e9e<\/p>\n<p>&#8211; Traiter administrativement les d\u00e9parts (clients et r\u00e9servataires) <\/p>\n<\/p>\n<\/p>\n<h2>Profil:<\/h2>\n<\/p>\n<p><strong>Profil souhait\u00e9 : <\/strong><\/p>\n<p>Formation commerciale ou immobili\u00e8re, de niveau Bac \u00e0 Bac + 2<\/p>\n<\/p>\n<p><strong>Particularit\u00e9s et contraintes :<\/strong><\/p>\n<p>Permis B : d\u00e9placements sur le secteur g\u00e9ographique de l\u2019agence (90)<\/p>\n<\/p>\n<p><strong>Pourquoi nous rejoindre ?<\/strong><\/p>\n<p>Parce que chez N\u00e9olia, tu ne seras pas seulement en alternance :<\/p>\n<p>tu seras accompagn\u00e9(e) form\u00e9(e) et impliqu\u00e9(e) dans des missions concr\u00e8tes qui te feront monter en comp\u00e9tences rapidement.<\/p>\n<\/p>\n<p><span style=\"font-size: 10pt\"><strong>Tu veux apprendre, progresser et faire la diff\u00e9rence d\u00e8s ton alternance ? Alors n\u2019attends plus :<\/strong><\/span><\/p>\n<p><span style=\"font-size: 10pt\"><strong>Rejoins-nous !<\/strong><\/span><\/p>\n<p><span style=\"font-size: 10pt\"><strong> <\/strong><\/span><\/p>\n<p style=\"text-align: center\"><strong><span style=\"font-size: 12pt\">Merci de postuler en parall\u00e8le de ce site sur :<\/span><\/strong><\/p>\n<p style=\"text-align: center\"><strong><span style=\"font-size: 12pt\"> https:\/\/besthr.com\/ats\/apps\/offer\/preview\/c032bf1e-47ab-45dc-99fc-96bd4fbe43ac<\/span><\/strong><\/p>\n<h3>Niveau de dipl\u00f4me:<\/h3>\n<p> BAC + 2 (BTS, DUT, DEUG, etc)<\/p>\n<h3>Sp\u00e9cialisations:<\/h3>\n<p>Marketing\/Commerce\/Ventes<\/p>\n","protected":false},"author":0,"featured_media":3646,"template":"","meta":{"_promoted":"","_job_location":"France, Grand-Est, 67 - Bas Rhin 20 Av. de la Paix","_application":"https:\/\/actionlogement-recrute.talent-soft.com\/offre-de-emploi\/emploi--conseiller-e-commercial-e-junior-alternance-strasbourg_17114.aspx?utm_source=monbailleur.fr","_company_name":"Action Logement","_company_website":"https:\/\/actionlogement-recrute.talent-soft.com\/","_company_tagline":"","_company_twitter":"","_company_video":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job-categories":[78],"job-types":[69],"class_list":{"0":"post-35116","1":"job_listing","2":"type-job_listing","3":"status-publish","4":"has-post-thumbnail","5":"hentry","6":"job_listing_category-autres","7":"job_listing_type-alternance","9":"job-type-alternance"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.4 (Yoast SEO v25.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Conseiller.e commercial.e Junior (Alternance) - Strasbourg - Monbailleur.fr - Emploi<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conseiller.e commercial.e Junior (Alternance) - Strasbourg\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;entreprise: Action Logement Groupe d\u00e9termine les orientations strat\u00e9giques du groupe Action Logement, les conditions d&#8217;emploi des ressources financi\u00e8res, et veille \u00e0 ce que les aides et les services soient distribu\u00e9s avec \u00e9quit\u00e9 entre les personnes \u00e9ligibles, dans tous les territoires. Description: A la rentr\u00e9e 2026, tu souhaites poursuivre ta formation en alternance dans une entreprise\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/conseiller-e-commercial-e-junior-alternance-strasbourg\" \/>\n<meta property=\"og:site_name\" content=\"Monbailleur.fr - Emploi\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/action-logement.png\" \/>\n\t<meta property=\"og:image:width\" content=\"175\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/conseiller-e-commercial-e-junior-alternance-strasbourg\",\"url\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/conseiller-e-commercial-e-junior-alternance-strasbourg\",\"name\":\"Conseiller.e commercial.e Junior (Alternance) - Strasbourg - Monbailleur.fr - Emploi\",\"isPartOf\":{\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/conseiller-e-commercial-e-junior-alternance-strasbourg#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/conseiller-e-commercial-e-junior-alternance-strasbourg#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/action-logement.png\",\"datePublished\":\"2026-03-13T06:00:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/conseiller-e-commercial-e-junior-alternance-strasbourg#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/conseiller-e-commercial-e-junior-alternance-strasbourg\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/conseiller-e-commercial-e-junior-alternance-strasbourg#primaryimage\",\"url\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/action-logement.png\",\"contentUrl\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/action-logement.png\",\"width\":175,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/conseiller-e-commercial-e-junior-alternance-strasbourg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"offres d\u2019emploi\",\"item\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/job-listings\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conseiller.e commercial.e Junior (Alternance) &#8211; Strasbourg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/#website\",\"url\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/\",\"name\":\"Monbailleur.fr - Emploi\",\"description\":\"Les offres d&#039;emploi du logement social\",\"publisher\":{\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/#organization\",\"name\":\"Monbailleur.fr - Emploi\",\"url\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/MonBailleur-1200x675-1.png\",\"contentUrl\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/MonBailleur-1200x675-1.png\",\"width\":1200,\"height\":675,\"caption\":\"Monbailleur.fr - Emploi\"},\"image\":{\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Conseiller.e commercial.e Junior (Alternance) - Strasbourg - Monbailleur.fr - Emploi","robots":{"index":"noindex","follow":"follow"},"og_locale":"fr_FR","og_type":"article","og_title":"Conseiller.e commercial.e Junior (Alternance) - Strasbourg","og_description":"L&rsquo;entreprise: Action Logement Groupe d\u00e9termine les orientations strat\u00e9giques du groupe Action Logement, les conditions d&#8217;emploi des ressources financi\u00e8res, et veille \u00e0 ce que les aides et les services soient distribu\u00e9s avec \u00e9quit\u00e9 entre les personnes \u00e9ligibles, dans tous les territoires. Description: A la rentr\u00e9e 2026, tu souhaites poursuivre ta formation en alternance dans une entreprise","og_url":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/conseiller-e-commercial-e-junior-alternance-strasbourg","og_site_name":"Monbailleur.fr - Emploi","og_image":[{"width":175,"height":200,"url":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/action-logement.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/conseiller-e-commercial-e-junior-alternance-strasbourg","url":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/conseiller-e-commercial-e-junior-alternance-strasbourg","name":"Conseiller.e commercial.e Junior (Alternance) - Strasbourg - Monbailleur.fr - Emploi","isPartOf":{"@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/conseiller-e-commercial-e-junior-alternance-strasbourg#primaryimage"},"image":{"@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/conseiller-e-commercial-e-junior-alternance-strasbourg#primaryimage"},"thumbnailUrl":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/action-logement.png","datePublished":"2026-03-13T06:00:10+00:00","breadcrumb":{"@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/conseiller-e-commercial-e-junior-alternance-strasbourg#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/conseiller-e-commercial-e-junior-alternance-strasbourg"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/conseiller-e-commercial-e-junior-alternance-strasbourg#primaryimage","url":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/action-logement.png","contentUrl":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/action-logement.png","width":175,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/conseiller-e-commercial-e-junior-alternance-strasbourg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.monbailleur.fr\/offres-emploi\/"},{"@type":"ListItem","position":2,"name":"offres d\u2019emploi","item":"https:\/\/www.monbailleur.fr\/offres-emploi\/job-listings"},{"@type":"ListItem","position":3,"name":"Conseiller.e commercial.e Junior (Alternance) &#8211; Strasbourg"}]},{"@type":"WebSite","@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/#website","url":"https:\/\/www.monbailleur.fr\/offres-emploi\/","name":"Monbailleur.fr - Emploi","description":"Les offres d&#039;emploi du logement social","publisher":{"@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.monbailleur.fr\/offres-emploi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/#organization","name":"Monbailleur.fr - Emploi","url":"https:\/\/www.monbailleur.fr\/offres-emploi\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/#\/schema\/logo\/image\/","url":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/MonBailleur-1200x675-1.png","contentUrl":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/MonBailleur-1200x675-1.png","width":1200,"height":675,"caption":"Monbailleur.fr - Emploi"},"image":{"@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/job-listings\/35116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/types\/job_listing"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/media\/3646"}],"wp:attachment":[{"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/media?parent=35116"}],"wp:term":[{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/job-categories?post=35116"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/job-types?post=35116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}