{"id":39246,"date":"2026-08-19T08:00:23","date_gmt":"2026-08-19T06:00:23","guid":{"rendered":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/gardien-dimmeubles-non-loge-cdd-cdc-habitat-social-69-h-f-2"},"modified":"2026-08-19T08:00:23","modified_gmt":"2026-08-19T06:00:23","slug":"gardien-dimmeubles-non-loge-cdd-cdc-habitat-social-69-h-f-2","status":"publish","type":"job_listing","link":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/gardien-dimmeubles-non-loge-cdd-cdc-habitat-social-69-h-f-2","title":{"rendered":"Gardien d&rsquo;Immeubles non log\u00e9 -CDD- CDC Habitat Social (69) H\/F"},"content":{"rendered":"<h2>L&rsquo;entreprise:<\/h2>\n<\/p>\n<p>Description de l&rsquo;entreprise:<\/p>\n<p>Rejoindre le groupe CDC Habitat, c&rsquo;est int\u00e9grer une entreprise au service de l&rsquo;habitat d&rsquo;int\u00e9r\u00eat public. Un groupe expert des m\u00e9tiers de la gestion locative, de la construction, de la r\u00e9novation de l&rsquo;habitat et de la ville. Un groupe engag\u00e9 pour r\u00e9pondre aux d\u00e9fis actuels. Un op\u00e9rateur global, pr\u00e9sent dans l&rsquo;Hexagone et les Outre-mer, qui offre \u00e0 ses 10 800 collaborateurs un cadre de travail bienveillant et la possibilit\u00e9 d&rsquo;agir concr\u00e8tement.<\/p>\n<p>Vous \u00e9voluerez au sein de la direction interr\u00e9gionale Auvergne Rh\u00f4ne-Alpes de CDC Habitat, bas\u00e9e \u00e0 Lyon et organis\u00e9e en un r\u00e9seau d&rsquo;agences de gestion locative situ\u00e9es \u00e0 Lyon, Grenoble, Annecy et Clermont-Ferrand. Nos 300 collaborateurs assurent la gestion et le d\u00e9veloppement d&rsquo;un patrimoine de plus de 25 000 logements sociaux, interm\u00e9diaires et abordables destin\u00e9s aux familles, aux \u00e9tudiants, jeunes actifs, aux personnes \u00e2g\u00e9es et personnes fragilis\u00e9es et\/ou en situation de handicap.<br \/>La Direction r\u00e9gionale Auvergne Rh\u00f4ne-Alpes est impliqu\u00e9e dans la d\u00e9marche \u00ab Objectif Employeur Pro V\u00e9lo \u00bb sur Lyon.<\/p>\n<p>CDC Habitat s&rsquo;engage en faveur de la diversit\u00e9, l&rsquo;\u00e9galit\u00e9 professionnelle, l&#8217;emploi des travailleurs handicap\u00e9s.<\/p>\n<h2>Description:<\/h2>\n<\/p>\n<p>Description de la mission:<\/p>\n<p>POSTE NON LOGE<\/p>\n<p>Sous la responsabilit\u00e9 du Responsable du secteur Ain Rh\u00f4ne Nord, au sein de l&rsquo;agence de Lyon, vous \u00eates l&rsquo;interlocuteur.trice privil\u00e9gi\u00e9.e des locataires au niveau de la proximit\u00e9. Vous est garant(e) aupr\u00e8s du client de la qualit\u00e9 du produit et des services.<\/p>\n<p>Les principales missions confi\u00e9es sont les suivantes :<\/p>\n<p>Entretien courant du patrimoine :<br \/>. R\u00e9aliser toute ou partie des t\u00e2ches de nettoyage des parties communes et abords imm\u00e9diats et de traitement des ordures m\u00e9nag\u00e8res. V\u00e9rifier le travail des entreprises de nettoyage.<\/p>\n<p>Maintenance et gestion technique du patrimoine :<br \/>. Contribuer au maintien de la s\u00e9curit\u00e9 des immeubles en assurant une surveillance des installations.<br \/>. Signaler pannes, anomalies, d\u00e9gradations, r\u00e9parations \u00e0 faire et, selon les proc\u00e9dures en vigueur, participer \u00e0 leur suivi de gestion.<br \/>. Commander de menus travaux et s&rsquo;assurer de leur r\u00e9alisation dans la limite d&rsquo;un seuil d&rsquo;engagement et sous la responsabilit\u00e9 du Responsable de secteur.<br \/>. Contr\u00f4ler les interventions des entreprises et participer \u00e0 des op\u00e9rations de r\u00e9ception de travaux, de r\u00e9habilitations.<br \/>. Traiter les r\u00e9clamations des locataires. Contr\u00f4ler la suite donn\u00e9e.<br \/>. Participer aux op\u00e9rations conduites par l&rsquo;entreprise en mati\u00e8re de d\u00e9veloppement durable.<\/p>\n<p>Gestion locative :<br \/>. Renseigner les candidats locataires et fournir aux locataires les informations portant notamment sur les lieux lou\u00e9s et leur environnement, le quartier, les documents adress\u00e9s par le bailleur (charges, travaux, fiches de visite\u2026) ; assurer les visites commerciales et la promotion de son site.<br \/>. G\u00e9rer les entr\u00e9es et sorties des locataires (visites, \u00e9tat des lieux entrants et sortants.<br \/>. Participer au recouvrement des loyers.<br \/>. Assurer la surveillance des logements vacants<br \/>. Participer \u00e0 la commercialisation, notamment en pr\u00e9sentant les caract\u00e9ristiques du logement, de ses accessoires, de son environnement.<br \/>. Assurer la liaison avec les services comp\u00e9tents en cas de conflit de voisinage, incivilit\u00e9s\u2026<br \/>. Informer les locataires (affichage, \u2026).<\/p>\n<p>Gestion sociale :<br \/>. Emettre un avis sur l&rsquo;adaptation et l&rsquo;\u00e9tat du logement lors de l&rsquo;affectation \u00e0 un locataire ou candidat.<br \/>. R\u00e9aliser un rappel au r\u00e8glement int\u00e9rieur en cas de conflit de voisinage, avant transmission aux services comp\u00e9tents.<br \/>. Communiquer aux services concern\u00e9s les situations anormales d&rsquo;occupation.<br \/>. Maintenir une relation de confiance avec les locataires en difficult\u00e9s notamment en cas d&rsquo;impay\u00e9s, les mettre en relation avec les personnes ressources (internes et externes).<\/p>\n<\/p>\n<h2>Profil:<\/h2>\n<\/p>\n<p>Profil:<\/p>\n<p>Exp\u00e9rience et connaissances requises :<br \/>. Niveau d&rsquo;\u00e9tudes minimum CAP.<br \/>. Exp\u00e9rience en gardiennage et nettoyage.<br \/>. Connaissances techniques second oeuvre appr\u00e9ci\u00e9es.<br \/>. Bonne ma\u00eetrise des outils bureautiques (MS Office). Logiciel utilis\u00e9 : IKOS.<br \/>. Parfaite ma\u00eetrise du fran\u00e7ais.<\/p>\n<p>QUALITES HUMAINES :<br \/>. Aisance relationnelle, diplomatie.<br \/>. Organisation et autonomie.<br \/>. Sens de l&rsquo;hygi\u00e8ne et de la propret\u00e9.<br \/>. Sens du service aux clients.<\/p>\n<p>Avantages sociaux :<br \/>. Temps de travail 37h\/semaine du lundi au vendredi et 15 RTT\/an.<br \/>. 29 jours de cong\u00e9s pay\u00e9s.<br \/>. 13\u00e8me mois, prime de vacances.<br \/>. Suppl\u00e9ment familial de traitement (sur justificatif enfants \u00e0 charge).<br \/>. Indemnit\u00e9 transport ou remboursement transport public sur justificatif \u00e0 hauteur de 75%.<br \/>. Carte d\u00e9jeuner 10,85 \u20ac par jour travaill\u00e9 (part employeur 60 %).<br \/>. Mutuelle familiale et pr\u00e9voyance.<\/p>\n<p>POSTE NON LOGE<\/p>\n<h3>Temps de travail<\/h3>\n<p>Temps plein <\/p>\n<h3> Organisme <\/h3>\n<p> <span id=\"ctl00_ctl00_AspMainContent_MainContent_MasterPageSettingsView_ctl03_ctl01_fldEntityDescriptionFormat_lblContentText\"><span id=\"ctl00_MainContent_DescriptionEntityEdit_SubForm1_ctl01_Field1_ctl00_lblEntityFormat\">CDC HABITAT <\/span><br \/><\/span><\/p>\n","protected":false},"author":0,"featured_media":5636,"template":"","meta":{"_promoted":"","_job_location":"France, Auvergne - Rhone-Alpes, Rh\u00f4ne (69) Avenue de l'Europe","_application":"https:\/\/les-hlm-recrutent.talent-soft.com\/offre-de-emploi\/emploi-gardien-d-immeubles-non-loge-cdd-cdc-habitat-social-69-h-f_70415.aspx?utm_source=monbailleur.fr","_company_name":"CDC HABITAT","_company_website":"","_company_tagline":"","_company_twitter":"","_company_video":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job-categories":[78],"job-types":[52],"class_list":["post-39246","job_listing","type-job_listing","status-publish","has-post-thumbnail","hentry","job_listing_category-autres","job_listing_type-cdd","job-type-cdd"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.4 (Yoast SEO v25.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gardien d&#039;Immeubles non log\u00e9 -CDD- CDC Habitat Social (69) H\/F - Monbailleur.fr - Emploi<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gardien d&#039;Immeubles non log\u00e9 -CDD- CDC Habitat Social (69) H\/F\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;entreprise: Description de l&rsquo;entreprise: Rejoindre le groupe CDC Habitat, c&rsquo;est int\u00e9grer une entreprise au service de l&rsquo;habitat d&rsquo;int\u00e9r\u00eat public. Un groupe expert des m\u00e9tiers de la gestion locative, de la construction, de la r\u00e9novation de l&rsquo;habitat et de la ville. Un groupe engag\u00e9 pour r\u00e9pondre aux d\u00e9fis actuels. Un op\u00e9rateur global, pr\u00e9sent dans l&rsquo;Hexagone et\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/gardien-dimmeubles-non-loge-cdd-cdc-habitat-social-69-h-f-2\" \/>\n<meta property=\"og:site_name\" content=\"Monbailleur.fr - Emploi\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/mon_bailleur_emploi_placeholder.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/gardien-dimmeubles-non-loge-cdd-cdc-habitat-social-69-h-f-2\",\"url\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/gardien-dimmeubles-non-loge-cdd-cdc-habitat-social-69-h-f-2\",\"name\":\"Gardien d'Immeubles non log\u00e9 -CDD- CDC Habitat Social (69) H\/F - Monbailleur.fr - Emploi\",\"isPartOf\":{\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/gardien-dimmeubles-non-loge-cdd-cdc-habitat-social-69-h-f-2#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/gardien-dimmeubles-non-loge-cdd-cdc-habitat-social-69-h-f-2#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/mon_bailleur_emploi_placeholder.png\",\"datePublished\":\"2026-08-19T06:00:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/gardien-dimmeubles-non-loge-cdd-cdc-habitat-social-69-h-f-2#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/gardien-dimmeubles-non-loge-cdd-cdc-habitat-social-69-h-f-2\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/gardien-dimmeubles-non-loge-cdd-cdc-habitat-social-69-h-f-2#primaryimage\",\"url\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/mon_bailleur_emploi_placeholder.png\",\"contentUrl\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/mon_bailleur_emploi_placeholder.png\",\"width\":512,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/gardien-dimmeubles-non-loge-cdd-cdc-habitat-social-69-h-f-2#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"offres d\u2019emploi\",\"item\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/job-listings\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gardien d&rsquo;Immeubles non log\u00e9 -CDD- CDC Habitat Social (69) H\/F\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/#website\",\"url\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/\",\"name\":\"Monbailleur.fr - Emploi\",\"description\":\"Les offres d&#039;emploi du logement social\",\"publisher\":{\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/#organization\",\"name\":\"Monbailleur.fr - Emploi\",\"url\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/MonBailleur-1200x675-1.png\",\"contentUrl\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/MonBailleur-1200x675-1.png\",\"width\":1200,\"height\":675,\"caption\":\"Monbailleur.fr - Emploi\"},\"image\":{\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gardien d'Immeubles non log\u00e9 -CDD- CDC Habitat Social (69) H\/F - Monbailleur.fr - Emploi","robots":{"index":"noindex","follow":"follow"},"og_locale":"fr_FR","og_type":"article","og_title":"Gardien d'Immeubles non log\u00e9 -CDD- CDC Habitat Social (69) H\/F","og_description":"L&rsquo;entreprise: Description de l&rsquo;entreprise: Rejoindre le groupe CDC Habitat, c&rsquo;est int\u00e9grer une entreprise au service de l&rsquo;habitat d&rsquo;int\u00e9r\u00eat public. Un groupe expert des m\u00e9tiers de la gestion locative, de la construction, de la r\u00e9novation de l&rsquo;habitat et de la ville. Un groupe engag\u00e9 pour r\u00e9pondre aux d\u00e9fis actuels. Un op\u00e9rateur global, pr\u00e9sent dans l&rsquo;Hexagone et","og_url":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/gardien-dimmeubles-non-loge-cdd-cdc-habitat-social-69-h-f-2","og_site_name":"Monbailleur.fr - Emploi","og_image":[{"width":512,"height":512,"url":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/mon_bailleur_emploi_placeholder.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/gardien-dimmeubles-non-loge-cdd-cdc-habitat-social-69-h-f-2","url":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/gardien-dimmeubles-non-loge-cdd-cdc-habitat-social-69-h-f-2","name":"Gardien d'Immeubles non log\u00e9 -CDD- CDC Habitat Social (69) H\/F - Monbailleur.fr - Emploi","isPartOf":{"@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/gardien-dimmeubles-non-loge-cdd-cdc-habitat-social-69-h-f-2#primaryimage"},"image":{"@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/gardien-dimmeubles-non-loge-cdd-cdc-habitat-social-69-h-f-2#primaryimage"},"thumbnailUrl":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/mon_bailleur_emploi_placeholder.png","datePublished":"2026-08-19T06:00:23+00:00","breadcrumb":{"@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/gardien-dimmeubles-non-loge-cdd-cdc-habitat-social-69-h-f-2#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/gardien-dimmeubles-non-loge-cdd-cdc-habitat-social-69-h-f-2"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/gardien-dimmeubles-non-loge-cdd-cdc-habitat-social-69-h-f-2#primaryimage","url":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/mon_bailleur_emploi_placeholder.png","contentUrl":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/mon_bailleur_emploi_placeholder.png","width":512,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/gardien-dimmeubles-non-loge-cdd-cdc-habitat-social-69-h-f-2#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.monbailleur.fr\/offres-emploi\/"},{"@type":"ListItem","position":2,"name":"offres d\u2019emploi","item":"https:\/\/www.monbailleur.fr\/offres-emploi\/job-listings"},{"@type":"ListItem","position":3,"name":"Gardien d&rsquo;Immeubles non log\u00e9 -CDD- CDC Habitat Social (69) H\/F"}]},{"@type":"WebSite","@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/#website","url":"https:\/\/www.monbailleur.fr\/offres-emploi\/","name":"Monbailleur.fr - Emploi","description":"Les offres d&#039;emploi du logement social","publisher":{"@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.monbailleur.fr\/offres-emploi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/#organization","name":"Monbailleur.fr - Emploi","url":"https:\/\/www.monbailleur.fr\/offres-emploi\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/#\/schema\/logo\/image\/","url":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/MonBailleur-1200x675-1.png","contentUrl":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/MonBailleur-1200x675-1.png","width":1200,"height":675,"caption":"Monbailleur.fr - Emploi"},"image":{"@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/job-listings\/39246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/types\/job_listing"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/media\/5636"}],"wp:attachment":[{"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/media?parent=39246"}],"wp:term":[{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/job-categories?post=39246"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/job-types?post=39246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}