{"id":39483,"date":"2026-08-29T08:00:29","date_gmt":"2026-08-29T06:00:29","guid":{"rendered":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/charge-de-pilotage-de-la-garantie-de-parfait-achevement-gpa-alternance-adoma-75-h-f"},"modified":"2026-08-29T08:00:29","modified_gmt":"2026-08-29T06:00:29","slug":"charge-de-pilotage-de-la-garantie-de-parfait-achevement-gpa-alternance-adoma-75-h-f","status":"publish","type":"job_listing","link":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/charge-de-pilotage-de-la-garantie-de-parfait-achevement-gpa-alternance-adoma-75-h-f","title":{"rendered":"Charg\u00e9 de pilotage de la Garantie de Parfait Ach\u00e8vement (GPA) &#8211; Alternance &#8211; Adoma (75) H\/F"},"content":{"rendered":"<h2>L&rsquo;entreprise:<\/h2>\n<p>CDC Habitat, anciennement Groupe SNI, est une filiale de la Caisse des d\u00e9p\u00f4ts et consignations ayant pour mission principale la gestion du patrimoine immobilier public. L&rsquo;entreprise g\u00e8re 348 725 logements. En 2005, le groupe SNI se transforme en op\u00e9rateur immobilier global.<\/p>\n<h2>Description:<\/h2>\n<\/p>\n<p><strong>Charg\u00e9 de pilotage de la Garantie de Parfait Ach\u00e8vement (GPA) H\/F \u2013 Alternance<\/strong><\/p>\n<p>Contrat d\u2019apprentissage (dur\u00e9e de 1 an)<\/p>\n<p>Poste \u00e0 pourvoir \u00e0 partir de septembre\/octobre 2026<\/p>\n<\/p>\n<p><span style=\"text-decoration: underline\"><strong>MISSION<\/strong><\/span><\/p>\n<p>Une mission d\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral<\/p>\n<p>Nos 3 000 collaborateurs veillent au quotidien \u00e0 un accompagnement de qualit\u00e9 au sein de nos r\u00e9sidences sociales et structures d\u2019h\u00e9bergement ayant pour vocation d\u2019accueillir un public en situation de pr\u00e9carit\u00e9 et de vuln\u00e9rabilit\u00e9 <\/p>\n<p>L\u2019activit\u00e9 ma\u00eetrise d\u2019ouvrage se traduit par des objectifs ambitieux de production de logements avec pr\u00e8s de 4 000 logements livr\u00e9s par an sur le territoire national pour un budget annuel d\u2019environ 150 millions d\u2019euros.<\/p>\n<p>Rattach\u00e9 \u00e0 la Direction du Patrimoine et plus particuli\u00e8rement au d\u00e9partement maitrise d\u2019ouvrage, vous contribuez \u00e0 l\u2019atteinte des objectifs ambitieux !<\/p>\n<p><strong>En tant que charg\u00e9(e) de pilotage de la Garantie de Parfait Ach\u00e8vement (GPA) agir concr\u00e8tement pour des projets vertueux, c\u2019est notamment :<\/strong><\/p>\n<p><strong> <\/strong><\/p>\n<p><strong>Assurer et accompagner :<\/strong><\/p>\n<\/p>\n<p>&#8211; La structuration du dispositif de suivi des garanties de parfait ach\u00e8vement, en lien avec les proc\u00e9dures internes en vigueur ;<\/p>\n<p>&#8211; L\u2019harmonisation des pratiques en d\u00e9ployant des outils communs, et en sensibilisant la fili\u00e8re ma\u00eetrise d\u2019ouvrage \u00e0 ces \u00e9volutions ;<\/p>\n<p>&#8211; La consolidation et la diffusion des retours d\u2019exp\u00e9riences, en contribuant \u00e0 l\u2019animation de groupes de travail en interne de la fili\u00e8re maitrise d\u2019ouvrage (en lien avec les op\u00e9rationnels) ;<\/p>\n<\/p>\n<p><strong>Contribuer \u00e0\/au :<\/strong><\/p>\n<\/p>\n<p>&#8211; Pilotage des indicateurs et m\u00e9thodes de suivi des r\u00e9serves et leurs lev\u00e9es ;<\/p>\n<p>&#8211; La production d\u2019analyses et retours d&rsquo;exp\u00e9riences visant \u00e0 identifier les facteurs de qualit\u00e9, les dysfonctionnements r\u00e9currents et les leviers d&rsquo;am\u00e9lioration des op\u00e9rations (ex : sur les techniques constructives (construction hors-site, \u00e9volutivit\u00e9, \u2026), performances \u00e9nerg\u00e9tiques et prise en compte du confort d\u2019\u00e9t\u00e9 des op\u00e9rations en cours de chantier et \/ ou livr\u00e9es) ;<\/p>\n<p>&#8211; Des \u00e9v\u00e9nements et groupes de travail ext\u00e9rieurs sur ces th\u00e9matiques ;<\/p>\n<p>&#8211; L\u2019\u00e9laboration de r\u00e9f\u00e9rentiels internes ;<\/p>\n<p>&#8211; Toutes autres missions ponctuelles au service de la qualit\u00e9 des op\u00e9rations ma\u00eetrise d\u2019ouvrage.<\/p>\n<h2>Profil:<\/h2>\n<\/p>\n<p><span style=\"text-decoration: underline\"><strong>PROFIL<\/strong><\/span><\/p>\n<p>Si vous aussi, vous voulez contribuer \u00e0 l\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral, au pilotage des projets nationaux de ma\u00eetrise d\u2019ouvrage et que :<\/p>\n<p>&#8211; Vous pr\u00e9parez une formation de niveau Bac +5 dans le domaine de la promotion immobili\u00e8re, des travaux publics ou de l\u2019habitat<\/p>\n<p>&#8211; Dot\u00e9(e) d\u2019une capacit\u00e9 d\u2019analyse et d\u2019un esprit de synth\u00e8se, vous faites preuve d\u2019une grande rigueur, de capacit\u00e9 d\u2019anticipation, d\u2019adaptation et d\u2019un esprit d\u2019initiative<\/p>\n<p>&#8211; Vous \u00eates reconnu(e) pour avoir de bonnes capacit\u00e9s relationnelles, d\u2019expression \u00e9crite et orale<\/p>\n<p>&#8211; Vous \u00eates \u00e0 l\u2019aise sur les outils bureautiques (M365)<\/p>\n<\/p>\n<p>Postulez au sein d\u2019une \u00e9quipe dynamique et investie !<\/p>\n<p>Lieu : poste bas\u00e9 \u00e0 Paris 13\u00e8me<\/p>\n<\/p>\n<p>Rejoindre Adoma,<\/p>\n<p>C\u2019est b\u00e9n\u00e9ficier d\u2019avantages :<\/p>\n<p>&#8211; Titres-restaurant \/ Restaurant d\u2019entreprise<\/p>\n<p>&#8211; Prime 13eme mois, prime vacances et \u00e9pargne salariale<\/p>\n<p>&#8211; Mutuelle et pr\u00e9voyance<\/p>\n<p>&#8211; Prise en charge des abonnements de transport \u00e0 75%<\/p>\n<p>&#8211; Prestations CSE<\/p>\n<p>&#8211; Salle de sport et conciergerie<\/p>\n<\/p>\n<p>C\u2019est aussi int\u00e9grer un environnement de travail bienveillant :<\/p>\n<p>&#8211; Un management attentif \u00e0 l\u2019\u00e9quilibre entre la vie professionnelle et la vie priv\u00e9e<\/p>\n<p>&#8211; Une entreprise respectueuse de la diversit\u00e9 et de l\u2019\u00e9galit\u00e9 de traitement professionnel entre toutes et tous<\/p>\n<p>&#8211; Une exp\u00e9rience riche et apprenante<\/p>\n<\/p>\n<p>Votre processus de recrutement se d\u00e9roulera en 2 \u00e9tapes :<\/p>\n<p>1. Un premier \u00e9change avec un membre de l\u2019\u00e9quipe RH<\/p>\n<p>2. Un \u00e9change avec le manager<\/p>\n<h3>Niveau de dipl\u00f4me:<\/h3>\n<p> BAC+4<\/p>\n<h3>Sp\u00e9cialisations:<\/h3>\n<ul>\n<li>DEVELOPPEMENT \/ MAITRISE D&rsquo;OUVRAGE<\/li>\n<li>A-MAITRISE D&rsquo;OUVRAGE &#8211; GESTION IMMOBILIERE<\/li>\n<\/ul>\n<h3> Entit\u00e9 de rattachement <\/h3>\n<p> En rejoignant Adoma, vous rejoignez un acteur de la solidarit\u00e9 engag\u00e9 pour le logement et l&rsquo;h\u00e9bergement des personnes en difficult\u00e9 : jeunes en insertion, travailleurs pr\u00e9caires, b\u00e9n\u00e9ficiaires de minima sociaux, travailleurs migrants, familles monoparentales. Pour nos 3 000 collaborateurs, l&rsquo;int\u00e9r\u00eat g\u00e9n\u00e9ral est au centre de nos pr\u00e9occupations avec une conviction qui nous anime : \u00ab un logement pour tous, c&rsquo;est un avenir pour chacun \u00bb. Nous accompagnons plus de 88 000 clients sur l&rsquo;ensemble du territoire. <br \/>Adoma est une filiale du groupe CDC Habitat. Un groupe partout dans l&rsquo;Hexagone et en Outre-mer o\u00f9 10 800 collaborateurs imaginent des solutions d&rsquo;habitat inclusives et durables au service des politiques publiques pour l&rsquo;am\u00e9nagement des quartiers et des territoires. <\/p>\n<p><\/p>\n","protected":false},"author":0,"featured_media":5636,"template":"","meta":{"_promoted":"","_job_location":"France, Ile-de-France, Paris (75) 33 Avenue Pierre Mend\u00e8s-France 75013 PARIS","_application":"https:\/\/emploi.cdc-habitat.com\/offre-de-emploi\/emploi-charge-de-pilotage-de-la-garantie-de-parfait-achevement-gpa-alternance-adoma-75-h-f_12754.aspx?utm_source=monbailleur.fr","_company_name":"CDC Habitat","_company_website":"https:\/\/www.cdc-habitat.fr\/","_company_tagline":"","_company_twitter":"","_company_video":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job-categories":[78],"job-types":[69],"class_list":["post-39483","job_listing","type-job_listing","status-publish","has-post-thumbnail","hentry","job_listing_category-autres","job_listing_type-alternance","job-type-alternance"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.4 (Yoast SEO v25.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Charg\u00e9 de pilotage de la Garantie de Parfait Ach\u00e8vement (GPA) - Alternance - Adoma (75) H\/F - Monbailleur.fr - Emploi<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Charg\u00e9 de pilotage de la Garantie de Parfait Ach\u00e8vement (GPA) - Alternance - Adoma (75) H\/F\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;entreprise: CDC Habitat, anciennement Groupe SNI, est une filiale de la Caisse des d\u00e9p\u00f4ts et consignations ayant pour mission principale la gestion du patrimoine immobilier public. L&rsquo;entreprise g\u00e8re 348 725 logements. En 2005, le groupe SNI se transforme en op\u00e9rateur immobilier global. Description: Charg\u00e9 de pilotage de la Garantie de Parfait Ach\u00e8vement (GPA) H\/F \u2013\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/charge-de-pilotage-de-la-garantie-de-parfait-achevement-gpa-alternance-adoma-75-h-f\" \/>\n<meta property=\"og:site_name\" content=\"Monbailleur.fr - Emploi\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/mon_bailleur_emploi_placeholder.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/charge-de-pilotage-de-la-garantie-de-parfait-achevement-gpa-alternance-adoma-75-h-f\",\"url\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/charge-de-pilotage-de-la-garantie-de-parfait-achevement-gpa-alternance-adoma-75-h-f\",\"name\":\"Charg\u00e9 de pilotage de la Garantie de Parfait Ach\u00e8vement (GPA) - Alternance - Adoma (75) H\/F - Monbailleur.fr - Emploi\",\"isPartOf\":{\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/charge-de-pilotage-de-la-garantie-de-parfait-achevement-gpa-alternance-adoma-75-h-f#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/charge-de-pilotage-de-la-garantie-de-parfait-achevement-gpa-alternance-adoma-75-h-f#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/mon_bailleur_emploi_placeholder.png\",\"datePublished\":\"2026-08-29T06:00:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/charge-de-pilotage-de-la-garantie-de-parfait-achevement-gpa-alternance-adoma-75-h-f#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/charge-de-pilotage-de-la-garantie-de-parfait-achevement-gpa-alternance-adoma-75-h-f\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/charge-de-pilotage-de-la-garantie-de-parfait-achevement-gpa-alternance-adoma-75-h-f#primaryimage\",\"url\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/mon_bailleur_emploi_placeholder.png\",\"contentUrl\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/mon_bailleur_emploi_placeholder.png\",\"width\":512,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/charge-de-pilotage-de-la-garantie-de-parfait-achevement-gpa-alternance-adoma-75-h-f#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"offres d\u2019emploi\",\"item\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/job-listings\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Charg\u00e9 de pilotage de la Garantie de Parfait Ach\u00e8vement (GPA) &#8211; Alternance &#8211; Adoma (75) H\/F\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/#website\",\"url\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/\",\"name\":\"Monbailleur.fr - Emploi\",\"description\":\"Les offres d&#039;emploi du logement social\",\"publisher\":{\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/#organization\",\"name\":\"Monbailleur.fr - Emploi\",\"url\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/MonBailleur-1200x675-1.png\",\"contentUrl\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/MonBailleur-1200x675-1.png\",\"width\":1200,\"height\":675,\"caption\":\"Monbailleur.fr - Emploi\"},\"image\":{\"@id\":\"https:\/\/www.monbailleur.fr\/offres-emploi\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Charg\u00e9 de pilotage de la Garantie de Parfait Ach\u00e8vement (GPA) - Alternance - Adoma (75) H\/F - Monbailleur.fr - Emploi","robots":{"index":"noindex","follow":"follow"},"og_locale":"fr_FR","og_type":"article","og_title":"Charg\u00e9 de pilotage de la Garantie de Parfait Ach\u00e8vement (GPA) - Alternance - Adoma (75) H\/F","og_description":"L&rsquo;entreprise: CDC Habitat, anciennement Groupe SNI, est une filiale de la Caisse des d\u00e9p\u00f4ts et consignations ayant pour mission principale la gestion du patrimoine immobilier public. L&rsquo;entreprise g\u00e8re 348 725 logements. En 2005, le groupe SNI se transforme en op\u00e9rateur immobilier global. Description: Charg\u00e9 de pilotage de la Garantie de Parfait Ach\u00e8vement (GPA) H\/F \u2013","og_url":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/charge-de-pilotage-de-la-garantie-de-parfait-achevement-gpa-alternance-adoma-75-h-f","og_site_name":"Monbailleur.fr - Emploi","og_image":[{"width":512,"height":512,"url":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/mon_bailleur_emploi_placeholder.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/charge-de-pilotage-de-la-garantie-de-parfait-achevement-gpa-alternance-adoma-75-h-f","url":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/charge-de-pilotage-de-la-garantie-de-parfait-achevement-gpa-alternance-adoma-75-h-f","name":"Charg\u00e9 de pilotage de la Garantie de Parfait Ach\u00e8vement (GPA) - Alternance - Adoma (75) H\/F - Monbailleur.fr - Emploi","isPartOf":{"@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/charge-de-pilotage-de-la-garantie-de-parfait-achevement-gpa-alternance-adoma-75-h-f#primaryimage"},"image":{"@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/charge-de-pilotage-de-la-garantie-de-parfait-achevement-gpa-alternance-adoma-75-h-f#primaryimage"},"thumbnailUrl":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/mon_bailleur_emploi_placeholder.png","datePublished":"2026-08-29T06:00:29+00:00","breadcrumb":{"@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/charge-de-pilotage-de-la-garantie-de-parfait-achevement-gpa-alternance-adoma-75-h-f#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/charge-de-pilotage-de-la-garantie-de-parfait-achevement-gpa-alternance-adoma-75-h-f"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/charge-de-pilotage-de-la-garantie-de-parfait-achevement-gpa-alternance-adoma-75-h-f#primaryimage","url":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/mon_bailleur_emploi_placeholder.png","contentUrl":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/mon_bailleur_emploi_placeholder.png","width":512,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/poste\/charge-de-pilotage-de-la-garantie-de-parfait-achevement-gpa-alternance-adoma-75-h-f#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.monbailleur.fr\/offres-emploi\/"},{"@type":"ListItem","position":2,"name":"offres d\u2019emploi","item":"https:\/\/www.monbailleur.fr\/offres-emploi\/job-listings"},{"@type":"ListItem","position":3,"name":"Charg\u00e9 de pilotage de la Garantie de Parfait Ach\u00e8vement (GPA) &#8211; Alternance &#8211; Adoma (75) H\/F"}]},{"@type":"WebSite","@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/#website","url":"https:\/\/www.monbailleur.fr\/offres-emploi\/","name":"Monbailleur.fr - Emploi","description":"Les offres d&#039;emploi du logement social","publisher":{"@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.monbailleur.fr\/offres-emploi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/#organization","name":"Monbailleur.fr - Emploi","url":"https:\/\/www.monbailleur.fr\/offres-emploi\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/#\/schema\/logo\/image\/","url":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/MonBailleur-1200x675-1.png","contentUrl":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-content\/uploads\/2023\/06\/MonBailleur-1200x675-1.png","width":1200,"height":675,"caption":"Monbailleur.fr - Emploi"},"image":{"@id":"https:\/\/www.monbailleur.fr\/offres-emploi\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/job-listings\/39483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/types\/job_listing"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/media\/5636"}],"wp:attachment":[{"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/media?parent=39483"}],"wp:term":[{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/job-categories?post=39483"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/www.monbailleur.fr\/offres-emploi\/wp-json\/wp\/v2\/job-types?post=39483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}